{"id":3113,"date":"2013-03-08T20:19:41","date_gmt":"2013-03-08T19:19:41","guid":{"rendered":"http:\/\/www.conservation-justice.org\/CJ\/?p=840"},"modified":"2013-03-08T20:19:41","modified_gmt":"2013-03-08T19:19:41","slug":"demantelement-dun-reseau-de-trafic-divoire-au-sud-gabon","status":"publish","type":"post","link":"https:\/\/www.conservation-justice.org\/fr\/demantelement-dun-reseau-de-trafic-divoire-au-sud-gabon\/","title":{"rendered":"D\u00e9mant\u00e8lement d&#8217;un r\u00e9seau de trafic d&#8217;ivoire au Sud Gabon"},"content":{"rendered":"<p><a href=\"http:\/\/www.conservation-justice.org\/CJ\/wp-content\/uploads\/2013\/03\/DSCF0374.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-841\" title=\"DSCF0374\" src=\"http:\/\/www.conservation-justice.org\/CJ\/wp-content\/uploads\/2013\/03\/DSCF0374-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/><\/a>Un mois apr\u00e8s une op\u00e9ration men\u00e9e \u00e0 Tchibanga par la Police Judiciaire gr\u00e2ce aux informations transmises par le projet AALF (Appui \u00e0 l\u2019Application de la Loi sur la Faune), partenariat entre le Minist\u00e8re des Eaux et For\u00eats et l\u2019ONG Conservation Justice, une deuxi\u00e8me op\u00e9ration a eu lieu. Un influent\u00a0 r\u00e9seau\u00a0 des trafiquants d\u2019ivoire a \u00e9t\u00e9 d\u00e9mantel\u00e9 \u00e0 Moabi le 27 F\u00e9vrier 2013.<\/p>\n<p>Lors d\u2019une transaction nocturne, l\u2019arrestation de deux membres du r\u00e9seau (NZIENGUI Eric Cabreyl et NGUIMBI Rudy Taylor) a pu \u00eatre assur\u00e9e. Leur chef, NGUIMBI KOUMBA Arcade dit Taylor, a malheureusement pris la fuite connaissant les risques encourus. Ce notable d\u2019apparence cr\u00e9dible de la localit\u00e9, d\u2019une cinquantaine d\u2019ann\u00e9es r\u00e9volues, \u00e9tait en effet \u00e0 la t\u00eate d\u2019un trafic d\u2019ivoire bien organis\u00e9. Ses \u00e9l\u00e9ments ont \u00e9t\u00e9 arr\u00eat\u00e9s avec six (6) pointes d\u2019ivoire de plus de 35 kilogrammes.<\/p>\n<p>Apr\u00e8s le d\u00e9ferrement des deux membres du r\u00e9seau \u00e0 Tchibanga et leur mise en d\u00e9tention \u00e0 la prison centrale de Tchibanga le 04 du mois de mars, il \u00e9tait \u00e9videmment question d\u2019arr\u00eater la t\u00eate du r\u00e9seau.<\/p>\n<p>Sept jours apr\u00e8s l\u2019arrestation de ses complices, et sous la pression familiale et des autorit\u00e9s, le notable en question d\u00e9cide de se rendre \u00e0 la Direction Provinciale des Eaux et Forets le 07 Mars 2013. Il est \u00e0 son tour entendu et plac\u00e9 \u00e0 garde \u00e0 vue dans les locaux de la Police Judiciaire de Tchibanga. Il sera\u00a0 pr\u00e9sent\u00e9 au Parquet et d\u00e9f\u00e9r\u00e9 \u00e0 la prison centrale de Tchibanga le lendemain, en attendant que la Justice d\u00e9cide de son sors. Apr\u00e8s l\u2019arrestation d\u2019un lieutenant de gendarmerie en janvier \u00e0 Tchibanga, du sous-pr\u00e9fet de Bolossoville, c\u2019est maintenant un notable politique d\u2019une localit\u00e9 qui fait les frais de ce type de trafic ill\u00e9gal.<\/p>\n<p><a href=\"http:\/\/www.gabonews.ga\/actualites-reader\/items\/demantelement-dun-reseau-de-trafic-divoire-a-moabi.html\">http:\/\/www.gabonews.ga\/actualites-reader\/items\/demantelement-dun-reseau-de-trafic-divoire-a-moabi.html<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"Un mois apr\u00e8s une op\u00e9ration men\u00e9e \u00e0 Tchibanga par la Police Judiciaire gr\u00e2ce aux informations transmises par le projet AALF (Appui \u00e0 l\u2019Application de la Loi sur la Faune), partenariat entre le Minist\u00e8re des Eaux et For\u00eats et l\u2019ONG Conservation Justice, une deuxi\u00e8me op\u00e9ration a eu lieu. Un influent\u00a0 r\u00e9seau\u00a0 des trafiquants d\u2019ivoire a \u00e9t\u00e9 [&hellip;]","protected":false},"author":4,"featured_media":1133,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3113","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee"],"_links":{"self":[{"href":"https:\/\/www.conservation-justice.org\/fr\/wp-json\/wp\/v2\/posts\/3113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.conservation-justice.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.conservation-justice.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.conservation-justice.org\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.conservation-justice.org\/fr\/wp-json\/wp\/v2\/comments?post=3113"}],"version-history":[{"count":0,"href":"https:\/\/www.conservation-justice.org\/fr\/wp-json\/wp\/v2\/posts\/3113\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.conservation-justice.org\/fr\/wp-json\/wp\/v2\/media\/1133"}],"wp:attachment":[{"href":"https:\/\/www.conservation-justice.org\/fr\/wp-json\/wp\/v2\/media?parent=3113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.conservation-justice.org\/fr\/wp-json\/wp\/v2\/categories?post=3113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.conservation-justice.org\/fr\/wp-json\/wp\/v2\/tags?post=3113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}